{"id":417,"date":"2024-06-25T12:25:13","date_gmt":"2024-06-25T10:25:13","guid":{"rendered":"https:\/\/nudeoexpo.art\/NoMore.photo\/?p=417"},"modified":"2024-06-25T12:31:52","modified_gmt":"2024-06-25T10:31:52","slug":"mon-ami-franck-musset-dans-openeye","status":"publish","type":"post","link":"https:\/\/nudeoexpo.art\/NoMore.photo\/mon-ami-franck-musset-dans-openeye\/","title":{"rendered":"Mon ami Franck Musset dans OpenEye"},"content":{"rendered":"<h3 style=\"text-align: center;\">Attentes et tentations : Les charmeuses et leur fakir<\/h3>\n<p>Il est ici des femmes travers\u00e9es par l\u2019ondoiement de leur corps aux troublantes transparences, aux poses soign\u00e9es et d\u00e9gag\u00e9es de l\u2019effet civilisateur du v\u00eatement. MUSSET (au nom id\u00e9al&#8230;) prouve que le sexe jamais n&rsquo;est vraiment apprivois\u00e9. Il est \u00e9rotis\u00e9 jusqu\u2019aux lois qui souvent r\u00eavent de le bannir. L\u2019ang\u00e9lique suggestion d&rsquo;un sein cr\u00e9e par exemple une apparition presque impalpable et comme au bord de l\u2019extinction. Au bord aussi d\u2019une renaissance.<\/p>\n<p>Ces corps sont dans la promesse d\u2019\u00e9clore. Ils s&rsquo;offrent et rarement se refusent par discr\u00e9tions allusives sans pour autant mettre le moindre b\u00e9mol sur la tentation de jouer \u00e9ventuellement d&rsquo;une fausse na\u00efvet\u00e9.<\/p>\n<p>De la nudit\u00e9 jaillit un v\u00e9ritable \u00ab cubisme \u00bb car le photographe joue sur un rendu simultan\u00e9 de facettes intimes et publiques. L&rsquo;intimit\u00e9 ne se remod\u00e8le pas selon nature, mais l&rsquo;artiste invite selon son regard \u00e0 une fouille arch\u00e9ologique symbolique, savante et attachante.<\/p>\n<p>Surgit le regard de l&rsquo;artiste sur la f\u00e9minit\u00e9 quasi absolue ouverte \u00e0 la vraie libert\u00e9. Celle qui fonde, qui brise, qui tend \u00e0 occuper tout l\u2019espace et faire le vide autour d&rsquo;elle. \u00c0 l&rsquo;inverse de ce regard d\u2019homme, la femme cr\u00e9e autour d&rsquo;elle une inflorescence qui la prolonge et l\u2019isole. La femme peut se voir en saltimbanque. Elle avance nue dans l&rsquo;imbroglio d\u2019une passementerie perverse. Elle prend, ang\u00e9lique parfois, les traits d\u2019un arch\u00e9type obsessionnel. L&rsquo;amour pour elle n&rsquo;est plus une menace assum\u00e9e mais un jeu de poup\u00e9e.<\/p>\n<p>Poup\u00e9e qui ne craint jamais l\u2019\u00e9panouissement \u00e9ph\u00e9m\u00e8re des roses du matin.<\/p>\n<p style=\"text-align: center;\">\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1821038629\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img title=\" \"loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"577\" src=\"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-content\/uploads\/Franck-Musset-768x577.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\" \" srcset=\"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-content\/uploads\/Franck-Musset-768x577.jpg 768w, https:\/\/nudeoexpo.art\/NoMore.photo\/wp-content\/uploads\/Franck-Musset-300x225.jpg 300w, https:\/\/nudeoexpo.art\/NoMore.photo\/wp-content\/uploads\/Franck-Musset.jpg 895w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1821038629 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n","protected":false},"excerpt":{"rendered":"<p>Attentes et tentations : Les charmeuses et leur fakir Il est ici des femmes travers\u00e9es par l\u2019ondoiement de leur corps aux troublantes transparences, aux poses soign\u00e9es et d\u00e9gag\u00e9es de l\u2019effet civilisateur du v\u00eatement. MUSSET (au nom id\u00e9al&#8230;) prouve que le sexe jamais n&rsquo;est vraiment apprivois\u00e9. Il est \u00e9rotis\u00e9 jusqu\u2019aux lois qui souvent r\u00eavent de le [&#8230;]\n","protected":false},"author":1,"featured_media":419,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parution"],"_links":{"self":[{"href":"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-json\/wp\/v2\/posts\/417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-json\/wp\/v2\/comments?post=417"}],"version-history":[{"count":6,"href":"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-json\/wp\/v2\/posts\/417\/revisions"}],"predecessor-version":[{"id":425,"href":"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-json\/wp\/v2\/posts\/417\/revisions\/425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-json\/wp\/v2\/media\/419"}],"wp:attachment":[{"href":"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-json\/wp\/v2\/media?parent=417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-json\/wp\/v2\/categories?post=417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nudeoexpo.art\/NoMore.photo\/wp-json\/wp\/v2\/tags?post=417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}